{"id":7026,"date":"2021-06-25T10:57:51","date_gmt":"2021-06-25T07:57:51","guid":{"rendered":"https:\/\/advokatveurope.com\/razdel-imushhestva-pri-rastorzhenii-braka-s-inostrancem\/"},"modified":"2021-07-05T11:02:56","modified_gmt":"2021-07-05T08:02:56","slug":"razdel-imushhestva-pri-rastorzhenii-braka-s-inostrancem","status":"publish","type":"page","link":"https:\/\/advokatveurope.com\/it\/razdel-imushhestva-pri-rastorzhenii-braka-s-inostrancem\/","title":{"rendered":"Divisione dei beni in caso di scioglimento del matrimonio con una persona straniera"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Il divorzio da una persona straniera all&#8217;estero \u00e8 un evento importante che provoca molte preoccupazioni e domande. Considera le sottigliezze legali associate a questo argomento. I <a href=\"https:\/\/advokatveurope.com\/\">Rapporti legali immobiliari all&#8217;estero<\/a> hanno determinate caratteristiche. La fine di una relazione matrimoniale spesso comporta <strong>divisione di beni all&#8217;estero<\/strong>&#8230; Qui dobbiamo prendere in considerazione le peculiarit\u00e0 della regolamentazione legale nei due paesi. Esistono controversie sulla propriet\u00e0?<\/p>\n<h2>Assistenza legale nella divisione dei beni all&#8217;estero<\/h2>\n<p>Molti credono che <strong>la divisione di propriet\u00e0 all&#8217;estero in caso di divorzio<\/strong> coinvolga soltanto le persone ricche. Ma anche i cittadini italiani comuni possono avere ville a Nizza, Bali, ecc. In fondo non c&#8217;\u00e8 da meravigliarsi se alcuni concittadini posseggono appartamenti in Francia, Spagna e altre localit\u00e0. E quanti beni sono registrati in un altro paese: auto, barche, ecc.<\/p>\n<p><strong>Divisione dei beni in caso di divorzio all&#8217;estero<\/strong> avviene secondo le regole dello Stato in cui \u00e8 avvenuto l&#8217;acquisto. Una <a href=\"https:\/\/advokatveurope.com\/uslugi\/\">Assistenza legale all&#8217;estero<\/a> \u00e8 necessaria e non solo durante l&#8217;intero processo di divorzio. \u00c8 necessaria:<\/p>\n<ul>\n<li>nella fase di conclusione di un contratto di matrimonio;<\/li>\n<li>per una traduzione e legalizzazione di documenti;<\/li>\n<li>quando si ricevono documenti all&#8217;estero.<\/li>\n<\/ul>\n<p>Ti aiuter\u00e0 una consulenza gratuita, che ti guider\u00e0 nella scelta del regime immobiliare per USA, Europa, Canada.<\/p>\n<h2>Come effettuare una divisione immobiliare all&#8217;estero<\/h2>\n<p>Per dividere i beni acquisiti congiuntamente nell&#8217;ordine istruttorio e giudiziale, sar\u00e0 necessario un <strong>avvocato esperto in divisione di beni all&#8217;estero<\/strong>&#8230; Un rappresentante qualificato aiuter\u00e0 le parti a determinare la giusta quota di propriet\u00e0.<\/p>\n<p>In una divisione pacifica, i coniugi redigono un elenco di tutti i beni. \u00c8 necessario accordarsi su chi otterr\u00e0 quale propriet\u00e0 e in quali proporzioni. Ci sono divisioni uguali e altre disuguali. Se i coniugi fanno un accordo, la legge non lo impedisce. Un avvocato aiuter\u00e0 a redigere e certificare un accordo scritto. Ciascun coniuge ricever\u00e0 la propria copia, sulla base della quale vengono presentati i documenti per la registrazione dei diritti sorti.<\/p>\n<p>Se si tratta di un tribunale, saranno divisi solo i beni acquistati all&#8217;estero.<\/p>\n<p>Un&#8217;ulteriore difficolt\u00e0 \u00e8 l&#8217;esecutivit\u00e0 delle decisioni giudiziarie. Ogni Stato ha i suoi principi di esecutivit\u00e0 e legalit\u00e0. Spesso i rapporti familiari con la partecipazione di stranieri sono associati a pi\u00f9 Stati con ordinamenti giuridici diversi. Il nostro avvocato ti aiuter\u00e0 a districarti nella giungla della legislazione straniera. Iscriviti per una consulenza![\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][wcube_it_contacts][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Il divorzio da una persona straniera all&#8217;estero \u00e8 un evento importante che provoca molte preoccupazioni e domande. Considera le sottigliezze legali associate a questo argomento. I Rapporti legali immobiliari all&#8217;estero hanno determinate caratteristiche. La fine di una relazione matrimoniale spesso comporta divisione di beni all&#8217;estero&#8230; Qui dobbiamo prendere in considerazione le peculiarit\u00e0 della regolamentazione legale&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7026","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0420\u0430\u0437\u0434\u0435\u043b \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430 \u043f\u0440\u0438 \u0440\u0430\u0441\u0442\u043e\u0440\u0436\u0435\u043d\u0438\u0438 \u0431\u0440\u0430\u043a\u0430 \u0441 \u0438\u043d\u043e\u0441\u0442\u0440\u0430\u043d\u0446\u0435\u043c. \u0410\u0434\u0432\u043e\u043a\u0430\u0442 \u0437\u0430 \u0440\u0443\u0431\u0435\u0436\u043e\u043c | Avvocato in Europa<\/title>\n<meta name=\"description\" content=\"\u042e\u0440\u0438\u0441\u0442 \u043f\u043e \u0432\u043e\u043f\u0440\u043e\u0441\u0430\u043c \u0440\u0430\u0437\u0434\u0435\u043b\u0430 \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430 \u0437\u0430 \u0440\u0443\u0431\u0435\u0436\u043e\u043c. \u042e\u0440\u0438\u0434\u0438\u0447\u0435\u0441\u043a\u0430\u044f \u043f\u043e\u043c\u043e\u0449\u044c \u0437\u0430 \u0433\u0440\u0430\u043d\u0438\u0446\u0435\u0439. \u0410\u0434\u0432\u043e\u043a\u0430\u0442 \u043f\u043e \u0440\u0430\u0437\u0434\u0435\u043b\u0443 \u0437\u0430\u0433\u0440\u0430\u043d\u0438\u0447\u043d\u043e\u0433\u043e \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430 \u043f\u0440\u0438 \u0440\u0430\u0437\u0432\u043e\u0434\u0435 \u0441 \u0438\u043d\u043e\u0441\u0442\u0440\u0430\u043d\u0446\u0435\u043c\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/advokatveurope.com\/it\/razdel-imushhestva-pri-rastorzhenii-braka-s-inostrancem\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0420\u0430\u0437\u0434\u0435\u043b \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430 \u043f\u0440\u0438 \u0440\u0430\u0441\u0442\u043e\u0440\u0436\u0435\u043d\u0438\u0438 \u0431\u0440\u0430\u043a\u0430 \u0441 \u0438\u043d\u043e\u0441\u0442\u0440\u0430\u043d\u0446\u0435\u043c. \u0410\u0434\u0432\u043e\u043a\u0430\u0442 \u0437\u0430 \u0440\u0443\u0431\u0435\u0436\u043e\u043c | Avvocato in Europa\" \/>\n<meta property=\"og:description\" content=\"\u042e\u0440\u0438\u0441\u0442 \u043f\u043e \u0432\u043e\u043f\u0440\u043e\u0441\u0430\u043c \u0440\u0430\u0437\u0434\u0435\u043b\u0430 \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430 \u0437\u0430 \u0440\u0443\u0431\u0435\u0436\u043e\u043c. \u042e\u0440\u0438\u0434\u0438\u0447\u0435\u0441\u043a\u0430\u044f \u043f\u043e\u043c\u043e\u0449\u044c \u0437\u0430 \u0433\u0440\u0430\u043d\u0438\u0446\u0435\u0439. \u0410\u0434\u0432\u043e\u043a\u0430\u0442 \u043f\u043e \u0440\u0430\u0437\u0434\u0435\u043b\u0443 \u0437\u0430\u0433\u0440\u0430\u043d\u0438\u0447\u043d\u043e\u0433\u043e \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430 \u043f\u0440\u0438 \u0440\u0430\u0437\u0432\u043e\u0434\u0435 \u0441 \u0438\u043d\u043e\u0441\u0442\u0440\u0430\u043d\u0446\u0435\u043c\" \/>\n<meta property=\"og:url\" content=\"https:\/\/advokatveurope.com\/it\/razdel-imushhestva-pri-rastorzhenii-braka-s-inostrancem\/\" \/>\n<meta property=\"og:site_name\" content=\"Avvocato in Europa\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-05T08:02:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/advokatveurope.com\/it\/razdel-imushhestva-pri-rastorzhenii-braka-s-inostrancem\/\",\"url\":\"https:\/\/advokatveurope.com\/it\/razdel-imushhestva-pri-rastorzhenii-braka-s-inostrancem\/\",\"name\":\"\u0420\u0430\u0437\u0434\u0435\u043b \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430 \u043f\u0440\u0438 \u0440\u0430\u0441\u0442\u043e\u0440\u0436\u0435\u043d\u0438\u0438 \u0431\u0440\u0430\u043a\u0430 \u0441 \u0438\u043d\u043e\u0441\u0442\u0440\u0430\u043d\u0446\u0435\u043c. \u0410\u0434\u0432\u043e\u043a\u0430\u0442 \u0437\u0430 \u0440\u0443\u0431\u0435\u0436\u043e\u043c | Avvocato in Europa\",\"isPartOf\":{\"@id\":\"https:\/\/advokatveurope.com\/#website\"},\"datePublished\":\"2021-06-25T07:57:51+00:00\",\"dateModified\":\"2021-07-05T08:02:56+00:00\",\"description\":\"\u042e\u0440\u0438\u0441\u0442 \u043f\u043e \u0432\u043e\u043f\u0440\u043e\u0441\u0430\u043c \u0440\u0430\u0437\u0434\u0435\u043b\u0430 \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430 \u0437\u0430 \u0440\u0443\u0431\u0435\u0436\u043e\u043c. \u042e\u0440\u0438\u0434\u0438\u0447\u0435\u0441\u043a\u0430\u044f \u043f\u043e\u043c\u043e\u0449\u044c \u0437\u0430 \u0433\u0440\u0430\u043d\u0438\u0446\u0435\u0439. \u0410\u0434\u0432\u043e\u043a\u0430\u0442 \u043f\u043e \u0440\u0430\u0437\u0434\u0435\u043b\u0443 \u0437\u0430\u0433\u0440\u0430\u043d\u0438\u0447\u043d\u043e\u0433\u043e \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430 \u043f\u0440\u0438 \u0440\u0430\u0437\u0432\u043e\u0434\u0435 \u0441 \u0438\u043d\u043e\u0441\u0442\u0440\u0430\u043d\u0446\u0435\u043c\",\"breadcrumb\":{\"@id\":\"https:\/\/advokatveurope.com\/it\/razdel-imushhestva-pri-rastorzhenii-braka-s-inostrancem\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/advokatveurope.com\/it\/razdel-imushhestva-pri-rastorzhenii-braka-s-inostrancem\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/advokatveurope.com\/it\/razdel-imushhestva-pri-rastorzhenii-braka-s-inostrancem\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\/\/advokatveurope.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Divisione dei beni in caso di scioglimento del matrimonio con una persona straniera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/advokatveurope.com\/#website\",\"url\":\"https:\/\/advokatveurope.com\/\",\"name\":\"\u00ab\u0410\u0434\u0432\u043e\u043a\u0430\u0442 \u0432 \u0415\u0432\u0440\u043e\u043f\u0435\u00bb\",\"description\":\"Pagamenti assicurativi in \u200b\u200bEuropa\",\"publisher\":{\"@id\":\"https:\/\/advokatveurope.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/advokatveurope.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/advokatveurope.com\/#organization\",\"name\":\"\u00abAvvocato in Europa\u00bb\",\"url\":\"https:\/\/advokatveurope.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/advokatveurope.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/advokatveurope.com\/wp-content\/uploads\/2020\/06\/logo-logo.png\",\"contentUrl\":\"https:\/\/advokatveurope.com\/wp-content\/uploads\/2020\/06\/logo-logo.png\",\"width\":80,\"height\":80,\"caption\":\"\u00abAvvocato in Europa\u00bb\"},\"image\":{\"@id\":\"https:\/\/advokatveurope.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0420\u0430\u0437\u0434\u0435\u043b \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430 \u043f\u0440\u0438 \u0440\u0430\u0441\u0442\u043e\u0440\u0436\u0435\u043d\u0438\u0438 \u0431\u0440\u0430\u043a\u0430 \u0441 \u0438\u043d\u043e\u0441\u0442\u0440\u0430\u043d\u0446\u0435\u043c. \u0410\u0434\u0432\u043e\u043a\u0430\u0442 \u0437\u0430 \u0440\u0443\u0431\u0435\u0436\u043e\u043c | Avvocato in Europa","description":"\u042e\u0440\u0438\u0441\u0442 \u043f\u043e \u0432\u043e\u043f\u0440\u043e\u0441\u0430\u043c \u0440\u0430\u0437\u0434\u0435\u043b\u0430 \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430 \u0437\u0430 \u0440\u0443\u0431\u0435\u0436\u043e\u043c. \u042e\u0440\u0438\u0434\u0438\u0447\u0435\u0441\u043a\u0430\u044f \u043f\u043e\u043c\u043e\u0449\u044c \u0437\u0430 \u0433\u0440\u0430\u043d\u0438\u0446\u0435\u0439. \u0410\u0434\u0432\u043e\u043a\u0430\u0442 \u043f\u043e \u0440\u0430\u0437\u0434\u0435\u043b\u0443 \u0437\u0430\u0433\u0440\u0430\u043d\u0438\u0447\u043d\u043e\u0433\u043e \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430 \u043f\u0440\u0438 \u0440\u0430\u0437\u0432\u043e\u0434\u0435 \u0441 \u0438\u043d\u043e\u0441\u0442\u0440\u0430\u043d\u0446\u0435\u043c","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/advokatveurope.com\/it\/razdel-imushhestva-pri-rastorzhenii-braka-s-inostrancem\/","og_locale":"it_IT","og_type":"article","og_title":"\u0420\u0430\u0437\u0434\u0435\u043b \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430 \u043f\u0440\u0438 \u0440\u0430\u0441\u0442\u043e\u0440\u0436\u0435\u043d\u0438\u0438 \u0431\u0440\u0430\u043a\u0430 \u0441 \u0438\u043d\u043e\u0441\u0442\u0440\u0430\u043d\u0446\u0435\u043c. \u0410\u0434\u0432\u043e\u043a\u0430\u0442 \u0437\u0430 \u0440\u0443\u0431\u0435\u0436\u043e\u043c | Avvocato in Europa","og_description":"\u042e\u0440\u0438\u0441\u0442 \u043f\u043e \u0432\u043e\u043f\u0440\u043e\u0441\u0430\u043c \u0440\u0430\u0437\u0434\u0435\u043b\u0430 \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430 \u0437\u0430 \u0440\u0443\u0431\u0435\u0436\u043e\u043c. \u042e\u0440\u0438\u0434\u0438\u0447\u0435\u0441\u043a\u0430\u044f \u043f\u043e\u043c\u043e\u0449\u044c \u0437\u0430 \u0433\u0440\u0430\u043d\u0438\u0446\u0435\u0439. \u0410\u0434\u0432\u043e\u043a\u0430\u0442 \u043f\u043e \u0440\u0430\u0437\u0434\u0435\u043b\u0443 \u0437\u0430\u0433\u0440\u0430\u043d\u0438\u0447\u043d\u043e\u0433\u043e \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430 \u043f\u0440\u0438 \u0440\u0430\u0437\u0432\u043e\u0434\u0435 \u0441 \u0438\u043d\u043e\u0441\u0442\u0440\u0430\u043d\u0446\u0435\u043c","og_url":"https:\/\/advokatveurope.com\/it\/razdel-imushhestva-pri-rastorzhenii-braka-s-inostrancem\/","og_site_name":"Avvocato in Europa","article_modified_time":"2021-07-05T08:02:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/advokatveurope.com\/it\/razdel-imushhestva-pri-rastorzhenii-braka-s-inostrancem\/","url":"https:\/\/advokatveurope.com\/it\/razdel-imushhestva-pri-rastorzhenii-braka-s-inostrancem\/","name":"\u0420\u0430\u0437\u0434\u0435\u043b \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430 \u043f\u0440\u0438 \u0440\u0430\u0441\u0442\u043e\u0440\u0436\u0435\u043d\u0438\u0438 \u0431\u0440\u0430\u043a\u0430 \u0441 \u0438\u043d\u043e\u0441\u0442\u0440\u0430\u043d\u0446\u0435\u043c. \u0410\u0434\u0432\u043e\u043a\u0430\u0442 \u0437\u0430 \u0440\u0443\u0431\u0435\u0436\u043e\u043c | Avvocato in Europa","isPartOf":{"@id":"https:\/\/advokatveurope.com\/#website"},"datePublished":"2021-06-25T07:57:51+00:00","dateModified":"2021-07-05T08:02:56+00:00","description":"\u042e\u0440\u0438\u0441\u0442 \u043f\u043e \u0432\u043e\u043f\u0440\u043e\u0441\u0430\u043c \u0440\u0430\u0437\u0434\u0435\u043b\u0430 \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430 \u0437\u0430 \u0440\u0443\u0431\u0435\u0436\u043e\u043c. \u042e\u0440\u0438\u0434\u0438\u0447\u0435\u0441\u043a\u0430\u044f \u043f\u043e\u043c\u043e\u0449\u044c \u0437\u0430 \u0433\u0440\u0430\u043d\u0438\u0446\u0435\u0439. \u0410\u0434\u0432\u043e\u043a\u0430\u0442 \u043f\u043e \u0440\u0430\u0437\u0434\u0435\u043b\u0443 \u0437\u0430\u0433\u0440\u0430\u043d\u0438\u0447\u043d\u043e\u0433\u043e \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430 \u043f\u0440\u0438 \u0440\u0430\u0437\u0432\u043e\u0434\u0435 \u0441 \u0438\u043d\u043e\u0441\u0442\u0440\u0430\u043d\u0446\u0435\u043c","breadcrumb":{"@id":"https:\/\/advokatveurope.com\/it\/razdel-imushhestva-pri-rastorzhenii-braka-s-inostrancem\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/advokatveurope.com\/it\/razdel-imushhestva-pri-rastorzhenii-braka-s-inostrancem\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/advokatveurope.com\/it\/razdel-imushhestva-pri-rastorzhenii-braka-s-inostrancem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/advokatveurope.com\/it\/"},{"@type":"ListItem","position":2,"name":"Divisione dei beni in caso di scioglimento del matrimonio con una persona straniera"}]},{"@type":"WebSite","@id":"https:\/\/advokatveurope.com\/#website","url":"https:\/\/advokatveurope.com\/","name":"\u00ab\u0410\u0434\u0432\u043e\u043a\u0430\u0442 \u0432 \u0415\u0432\u0440\u043e\u043f\u0435\u00bb","description":"Pagamenti assicurativi in \u200b\u200bEuropa","publisher":{"@id":"https:\/\/advokatveurope.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/advokatveurope.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/advokatveurope.com\/#organization","name":"\u00abAvvocato in Europa\u00bb","url":"https:\/\/advokatveurope.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/advokatveurope.com\/#\/schema\/logo\/image\/","url":"https:\/\/advokatveurope.com\/wp-content\/uploads\/2020\/06\/logo-logo.png","contentUrl":"https:\/\/advokatveurope.com\/wp-content\/uploads\/2020\/06\/logo-logo.png","width":80,"height":80,"caption":"\u00abAvvocato in Europa\u00bb"},"image":{"@id":"https:\/\/advokatveurope.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/advokatveurope.com\/it\/wp-json\/wp\/v2\/pages\/7026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/advokatveurope.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/advokatveurope.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/advokatveurope.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/advokatveurope.com\/it\/wp-json\/wp\/v2\/comments?post=7026"}],"version-history":[{"count":2,"href":"https:\/\/advokatveurope.com\/it\/wp-json\/wp\/v2\/pages\/7026\/revisions"}],"predecessor-version":[{"id":7030,"href":"https:\/\/advokatveurope.com\/it\/wp-json\/wp\/v2\/pages\/7026\/revisions\/7030"}],"wp:attachment":[{"href":"https:\/\/advokatveurope.com\/it\/wp-json\/wp\/v2\/media?parent=7026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}